{"id":36761,"date":"2014-11-15T02:11:32","date_gmt":"2014-11-15T02:11:32","guid":{"rendered":"https:\/\/maison-chance.org\/on-the-way-to-dak-nong.html"},"modified":"2022-02-23T16:25:22","modified_gmt":"2022-02-23T09:25:22","slug":"en-route-pour-daknong","status":"publish","type":"post","link":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html","title":{"rendered":"En route pour Daknong"},"content":{"rendered":"<p style=\"text-align: justify;\">Une fois encore nous avons pris la route pour Dak Nong. L\u2019objectif de notre voyage est de mener des enqu\u00eates sociales, de rencontrer de personnes handicap\u00e9es et des orphelins et d\u2019\u00e9tudier les techniques agricoles de la r\u00e9gion.<\/p>\n<p style=\"text-align: justify;\">Nous avons commenc\u00e9 notre s\u00e9jour par la visite du centre d\u2019accueil pour personnes handicap\u00e9es mentales de s\u0153ur Oanh, o\u00f9 elle pratique la th\u00e9rapie avec les animaux : lapins, poules, chiens, cochons d\u2019Inde\u2026<\/p>\n<p style=\"text-align: justify;\">Les pensionnaires du centre ont \u00e9galement la responsabilit\u00e9 d\u2019un potager biologique qui leur fournit quotidiennement les l\u00e9gumes dont ils ont besoin.<\/p>\n<p style=\"text-align: center;\">[robo-gallery id=\u00a0\u00bb36670&Prime;]\n","protected":false},"excerpt":{"rendered":"<p>Une fois encore nous avons pris la route pour Dak Nong. L\u2019objectif de notre voyage est de mener des enqu\u00eates sociales, de rencontrer de personnes handicap\u00e9es et des orphelins et d\u2019\u00e9tudier les techniques agricoles de la r\u00e9gion. Nous avons commenc\u00e9 notre s\u00e9jour par la visite du centre d\u2019accueil pour personnes handicap\u00e9es mentales de s\u0153ur Oanh, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":36733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[28],"tags":[493,494,495,496,497],"class_list":["post-36761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dernieres-nouvelles","tag-nguoi-khuyet-tat-en-de-fr","tag-nong-nghiep-en-de-fr","tag-tap-vat-ly-tri-lieu-en-de-fr","tag-tay-nguyen-en-de-fr","tag-xa-hoi-en-de-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En route pour Daknong<\/title>\n<meta name=\"description\" content=\"Une fois encore nous avons pris la route pour Dak Nong. L\u2019objectif de notre voyage est de mener des enqu\u00eates sociales, de rencontrer...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0110\u01b0\u1eddng \u0111\u1ebfn \u0110\u1eafk N\u00f4ng!\" \/>\n<meta property=\"og:description\" content=\"trung t\u00e2m d\u00e0nh cho nh\u1eefng ng\u01b0\u1eddi khuy\u1ebft t\u1eadt thi\u1ec3u n\u0103ng tr\u00ed tu\u1ec7, t\u1eadp v\u1eadt l\u00fd tr\u1ecb li\u1ec7u v\u1edbi \u0111\u1ed9ng v\u1eadt nh\u01b0: th\u1ecf, g\u00e0, ch\u00f3, heo m\u1ecdi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html\" \/>\n<meta property=\"og:site_name\" content=\"Maison Chance Association\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MaisonChance\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-15T02:11:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-23T09:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maison-chance.org\/wp-content\/uploads\/2022\/02\/On-the-way-to-Dak-Nong16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MaisonChanceVN\" \/>\n<meta name=\"twitter:site\" content=\"@MaisonChanceVN\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#\\\/schema\\\/person\\\/add65e5a4e55a3f32cde9a55c8835a85\"},\"headline\":\"En route pour Daknong\",\"datePublished\":\"2014-11-15T02:11:32+00:00\",\"dateModified\":\"2022-02-23T09:25:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html\"},\"wordCount\":108,\"publisher\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maison-chance.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/On-the-way-to-Dak-Nong16.jpg\",\"keywords\":[\"ng\u01b0\u1eddi khuy\u1ebft t\u1eadt\",\"n\u00f4ng nghi\u1ec7p\",\"t\u1eadp v\u1eadt l\u00fd tr\u1ecb li\u1ec7u\",\"T\u00e2y Nguy\u00ean\",\"x\u00e3 h\u1ed9i\"],\"articleSection\":[\"Derni\u00e8res Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html\",\"url\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html\",\"name\":\"En route pour Daknong\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maison-chance.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/On-the-way-to-Dak-Nong16.jpg\",\"datePublished\":\"2014-11-15T02:11:32+00:00\",\"dateModified\":\"2022-02-23T09:25:22+00:00\",\"description\":\"Une fois encore nous avons pris la route pour Dak Nong. L\u2019objectif de notre voyage est de mener des enqu\u00eates sociales, de rencontrer...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#primaryimage\",\"url\":\"https:\\\/\\\/maison-chance.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/On-the-way-to-Dak-Nong16.jpg\",\"contentUrl\":\"https:\\\/\\\/maison-chance.org\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/On-the-way-to-Dak-Nong16.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/en-route-pour-daknong.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Derni\u00e8res Nouvelles\",\"item\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/dernieres-nouvelles\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En route pour Daknong\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#website\",\"url\":\"https:\\\/\\\/maison-chance.org\\\/fr\",\"name\":\"https:\\\/\\\/maison-chance.org\\\/\",\"description\":\"Un avenir pour les moins chanceaux au Vietnam !\",\"publisher\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maison-chance.org\\\/fr?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#organization\",\"name\":\"https:\\\/\\\/maison-chance.org\\\/\",\"url\":\"https:\\\/\\\/maison-chance.org\\\/fr\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maison-chance.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Featued-Logo-MC-1.jpg\",\"contentUrl\":\"https:\\\/\\\/maison-chance.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Featued-Logo-MC-1.jpg\",\"width\":500,\"height\":313,\"caption\":\"https:\\\/\\\/maison-chance.org\\\/\"},\"image\":{\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MaisonChance\",\"https:\\\/\\\/x.com\\\/MaisonChanceVN\",\"https:\\\/\\\/www.instagram.com\\\/maisonchance\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MaisonChanceVideo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maison-chance.org\\\/fr#\\\/schema\\\/person\\\/add65e5a4e55a3f32cde9a55c8835a85\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/660d2983d889156339f43a36a35c2abc88137725f8369e14f3e7ea37a7a1587e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/660d2983d889156339f43a36a35c2abc88137725f8369e14f3e7ea37a7a1587e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/660d2983d889156339f43a36a35c2abc88137725f8369e14f3e7ea37a7a1587e?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/maison-chance.org\\\/fr\\\/author\\\/mcadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En route pour Daknong","description":"Une fois encore nous avons pris la route pour Dak Nong. L\u2019objectif de notre voyage est de mener des enqu\u00eates sociales, de rencontrer...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html","og_locale":"fr_FR","og_type":"article","og_title":"\u0110\u01b0\u1eddng \u0111\u1ebfn \u0110\u1eafk N\u00f4ng!","og_description":"trung t\u00e2m d\u00e0nh cho nh\u1eefng ng\u01b0\u1eddi khuy\u1ebft t\u1eadt thi\u1ec3u n\u0103ng tr\u00ed tu\u1ec7, t\u1eadp v\u1eadt l\u00fd tr\u1ecb li\u1ec7u v\u1edbi \u0111\u1ed9ng v\u1eadt nh\u01b0: th\u1ecf, g\u00e0, ch\u00f3, heo m\u1ecdi","og_url":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html","og_site_name":"Maison Chance Association","article_publisher":"https:\/\/www.facebook.com\/MaisonChance","article_published_time":"2014-11-15T02:11:32+00:00","article_modified_time":"2022-02-23T09:25:22+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/maison-chance.org\/wp-content\/uploads\/2022\/02\/On-the-way-to-Dak-Nong16.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@MaisonChanceVN","twitter_site":"@MaisonChanceVN","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#article","isPartOf":{"@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html"},"author":{"name":"Admin","@id":"https:\/\/maison-chance.org\/fr#\/schema\/person\/add65e5a4e55a3f32cde9a55c8835a85"},"headline":"En route pour Daknong","datePublished":"2014-11-15T02:11:32+00:00","dateModified":"2022-02-23T09:25:22+00:00","mainEntityOfPage":{"@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html"},"wordCount":108,"publisher":{"@id":"https:\/\/maison-chance.org\/fr#organization"},"image":{"@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#primaryimage"},"thumbnailUrl":"https:\/\/maison-chance.org\/wp-content\/uploads\/2022\/02\/On-the-way-to-Dak-Nong16.jpg","keywords":["ng\u01b0\u1eddi khuy\u1ebft t\u1eadt","n\u00f4ng nghi\u1ec7p","t\u1eadp v\u1eadt l\u00fd tr\u1ecb li\u1ec7u","T\u00e2y Nguy\u00ean","x\u00e3 h\u1ed9i"],"articleSection":["Derni\u00e8res Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html","url":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html","name":"En route pour Daknong","isPartOf":{"@id":"https:\/\/maison-chance.org\/fr#website"},"primaryImageOfPage":{"@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#primaryimage"},"image":{"@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#primaryimage"},"thumbnailUrl":"https:\/\/maison-chance.org\/wp-content\/uploads\/2022\/02\/On-the-way-to-Dak-Nong16.jpg","datePublished":"2014-11-15T02:11:32+00:00","dateModified":"2022-02-23T09:25:22+00:00","description":"Une fois encore nous avons pris la route pour Dak Nong. L\u2019objectif de notre voyage est de mener des enqu\u00eates sociales, de rencontrer...","breadcrumb":{"@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#primaryimage","url":"https:\/\/maison-chance.org\/wp-content\/uploads\/2022\/02\/On-the-way-to-Dak-Nong16.jpg","contentUrl":"https:\/\/maison-chance.org\/wp-content\/uploads\/2022\/02\/On-the-way-to-Dak-Nong16.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/maison-chance.org\/fr\/en-route-pour-daknong.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Derni\u00e8res Nouvelles","item":"https:\/\/maison-chance.org\/fr\/dernieres-nouvelles"},{"@type":"ListItem","position":2,"name":"En route pour Daknong"}]},{"@type":"WebSite","@id":"https:\/\/maison-chance.org\/fr#website","url":"https:\/\/maison-chance.org\/fr","name":"https:\/\/maison-chance.org\/","description":"Un avenir pour les moins chanceaux au Vietnam !","publisher":{"@id":"https:\/\/maison-chance.org\/fr#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maison-chance.org\/fr?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/maison-chance.org\/fr#organization","name":"https:\/\/maison-chance.org\/","url":"https:\/\/maison-chance.org\/fr","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/maison-chance.org\/fr#\/schema\/logo\/image\/","url":"https:\/\/maison-chance.org\/wp-content\/uploads\/2021\/09\/Featued-Logo-MC-1.jpg","contentUrl":"https:\/\/maison-chance.org\/wp-content\/uploads\/2021\/09\/Featued-Logo-MC-1.jpg","width":500,"height":313,"caption":"https:\/\/maison-chance.org\/"},"image":{"@id":"https:\/\/maison-chance.org\/fr#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MaisonChance","https:\/\/x.com\/MaisonChanceVN","https:\/\/www.instagram.com\/maisonchance\/","https:\/\/www.youtube.com\/c\/MaisonChanceVideo"]},{"@type":"Person","@id":"https:\/\/maison-chance.org\/fr#\/schema\/person\/add65e5a4e55a3f32cde9a55c8835a85","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/660d2983d889156339f43a36a35c2abc88137725f8369e14f3e7ea37a7a1587e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/660d2983d889156339f43a36a35c2abc88137725f8369e14f3e7ea37a7a1587e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/660d2983d889156339f43a36a35c2abc88137725f8369e14f3e7ea37a7a1587e?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/maison-chance.org\/fr\/author\/mcadmin"}]}},"_links":{"self":[{"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/posts\/36761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/comments?post=36761"}],"version-history":[{"count":1,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/posts\/36761\/revisions"}],"predecessor-version":[{"id":36762,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/posts\/36761\/revisions\/36762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/media\/36733"}],"wp:attachment":[{"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/media?parent=36761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/categories?post=36761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maison-chance.org\/fr\/wp-json\/wp\/v2\/tags?post=36761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}